{"id":593,"date":"2016-07-01T12:21:12","date_gmt":"2016-07-01T10:21:12","guid":{"rendered":"http:\/\/www.battenstein.com\/blog\/?p=593"},"modified":"2016-07-01T12:21:12","modified_gmt":"2016-07-01T10:21:12","slug":"selbstausbeutung-von-familienangehoerigen-im-familienbetrieb-taetigkeit-wie-ein-versicherter","status":"publish","type":"post","link":"https:\/\/www.battenstein.com\/blog\/2016\/07\/01\/selbstausbeutung-von-familienangehoerigen-im-familienbetrieb-taetigkeit-wie-ein-versicherter\/","title":{"rendered":"Selbstausbeutung von Familienangeh\u00f6rigen im Familienbetrieb, T\u00e4tigkeit wie ein Versicherter"},"content":{"rendered":"<p>In der gesetzlichen Unfallversicherung hat man seinerzeit eine Vorschrift eingebracht, \u00a7 539 Abs. 2 RVO, die arbeitnehmer\u00e4hnliche T\u00e4tigkeiten von Familienangeh\u00f6rigen unter Versicherungsschutz stellte.<\/p>\n<p>Ansonsten w\u00fcrden langj\u00e4hrig Besch\u00e4ftige in einem Familienunternehmen bei Abeitsunfall oder Berufskrankheit leer ausgehen, etwa die Ehefrau oder die Kinder oder sonstige Verwandte.<\/p>\n<p>Interessant ist diese T\u00e4tigkeit wie ein Versicherter im Falle eines Arbeitsunfalls oder einer Berufskrankheit 1317, Polyneuropathie oder Enzephalopathie durch die Einwirkung von organischen L\u00f6sungsmitteln.<\/p>\n<p>Zunehmend aber erkl\u00e4ren offenbar die Sozialgerichte diese T\u00e4tigkeiten von Familienangeh\u00f6rigen zu unternehmerischen T\u00e4tigkeiten, obwohl man in einem Reinigungsbetrieb sich nicht vorstellen kann, da\u00df dort \u00fcberhaupt unternehmerische T\u00e4tigkeiten stattfinden.<\/p>\n<p>Bemerkenswert ist der Fall des Sozialgerichts D\u00fcsseldorf, S 6 U 522\/13.<\/p>\n<p>Dort hie\u00df das Unternehmen des Ehemannes ausdr\u00fccklich Udo Reinigungscenter&#8230;<\/p>\n<p>Gleichwohl erkl\u00e4rte das Sozialgericht die Ehefrau, die jahrzehntelang in diesem Unternehmen t\u00e4tig war, zur Unternehmerin oder Mitunternehmerin.<\/p>\n<p>Es entscheiden die tats\u00e4chlichen Verh\u00e4ltnisse und nicht, wie sich die Kl\u00e4gerin wohl m\u00f6glicherweise ungl\u00fccklich ausdr\u00fcckt, indem sie etwa von unserem Betrieb spricht.<\/p>\n<p>Eine solche Identifikation mit dem Unternehmen schlie\u00dft die Versicherteneigenschaft allerdings keineswegs aus, wie andere F\u00e4lle zeigen.<\/p>\n<p>F\u00fcr die Ehefrau ist es eine Frage, ob nun ihre Berufskrankheit 1317, Polyneuropathie oder Enzephalopathie, entsch\u00e4digt wird oder nicht.<\/p>\n<p>Es gilt die Auslegungsvorschrift des \u00a7 2 Abs. 2 SGB I, danach soll sichergestellt werden, und zwar zwingend, da\u00df die sozialen Rechte des Betroffenen m\u00f6glich weitgehend verwirklicht werden bei der Auslegung der sozialrechtlichen Vorschriften.<\/p>\n<p>Die Erkl\u00e4rung zu Unternehmern in den F\u00e4llen des \u00a7 539 II RVO bzw. \u00a7 2 Abs. 2 SGB VII ist ein ernstzunehmender Mi\u00dfstand.<\/p>\n<p>Die Folge ist der Verlust des Versicherungsschutzes sowie auch zum Teil erhebliche Sch\u00e4den, z. B. beim Pleuramesotheliom bzw. Rippenfellkrebs durch Asbest von Ehefrau und Kindern, die jahrelang die asbestverschmutze Arbeitskleidung des Familienvaters reinigten, welche dieser von der Arbeit mit nach Hause brachte.<\/p>\n<p>Rechtsanwalt<br \/>\nFachanwalt f\u00fcr Sozialrecht<\/p>\n","protected":false},"excerpt":{"rendered":"In der gesetzlichen Unfallversicherung hat man seinerzeit eine Vorschrift eingebracht, die arbeitnehmer\u00e4hnliche T\u00e4tigkeiten von Familienangeh\u00f6rigen unter Versicherungsschutz stellte.","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,119,121],"tags":[25,75,870,871,873,80,872,151],"class_list":["post-593","post","type-post","status-publish","format-standard","hentry","category-allgemein","category-arbeitsunfalle-rechtsprechung-zum-arbeitsunfall","category-berufskrankheiten-rechtsprechung-zur-berufskrankheit","tag-arbeitsunfall","tag-berufskrankheit","tag-familie","tag-familienunternehmen","tag-missstand","tag-tatigkeit","tag-versichert","tag-versicherungsschutz","entry"],"_links":{"self":[{"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/posts\/593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/comments?post=593"}],"version-history":[{"count":1,"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/posts\/593\/revisions"}],"predecessor-version":[{"id":594,"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/posts\/593\/revisions\/594"}],"wp:attachment":[{"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/media?parent=593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/categories?post=593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.battenstein.com\/blog\/wp-json\/wp\/v2\/tags?post=593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}